{"id":7264,"date":"2026-01-15T09:15:59","date_gmt":"2026-01-15T09:15:59","guid":{"rendered":"https:\/\/www.phase-6.de\/magazin\/?p=7264"},"modified":"2026-02-03T15:29:36","modified_gmt":"2026-02-03T15:29:36","slug":"vokabeltest-generator-automatisch-vokabeltests-erstellen","status":"publish","type":"post","link":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/","title":{"rendered":"Automatisch Vokabeltests erstellen und bewerten"},"content":{"rendered":"[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text admin_label=&#8220;Einleitung&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<p><span style=\"font-weight: 400;\">Dass Lehrende nicht viel zu tun haben, ist ein Klischee, das sich eisern h\u00e4lt. Sie wissen jedoch besser als alle anderen, dass das zumeist nicht der Wahrheit entspricht. Denn die Zeit, die Sie in der Schule verbringen, deckt nur einen kleinen Teil Ihres Aufgabenfeldes ab. Ein gro\u00dfer Teil Ihrer Zeit flie\u00dft in die Vor- und Nachbereitung des Unterrichts. <\/span>Hinzu kommt das Erstellen und vor allem das Kontrollieren von Aufgaben. Gerade als Lehrkraft f\u00fcr Fremdsprachen werden Sie vom stetigen Korrigieren \u00e4hnlicher Fehler in Vokabeltests oder Klassenarbeiten ein Lied singen k\u00f6nnen \u2013 nicht die anregendste Aufgabe, oder was sagen Sie?<\/p>\n[\/et_pb_text][et_pb_blurb title=&#8220;Inhalt:&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x64;||divi||400&#8243; icon_placement=&#8220;left&#8220; disabled_on=&#8220;off|off|off&#8220; admin_label=&#8220;Inhaltsverzeichnis&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#757575&#8243; header_line_height=&#8220;1.2em&#8220; body_line_height=&#8220;1.2em&#8220; background_color=&#8220;rgba(214,214,214,0.25)&#8220; max_width=&#8220;70%&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_margin=&#8220;40px|10px|40px|10px|false|false&#8220; custom_padding=&#8220;40px|10px|40px|10px|false|false&#8220; animation_style=&#8220;fold&#8220; animation=&#8220;off&#8220; custom_css_main_element=&#8220;  z-index: 9999;&#8220; custom_css_blurb_title=&#8220;padding-bottom: 20px&#8220; border_radii=&#8220;on|2px|2px|2px|2px&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;#e0e0e0&#8243; border_style_all=&#8220;solid&#8220; use_border_color=&#8220;on&#8220; border_color=&#8220;#f2f4f4&#8243; border_width=&#8220;3px&#8220; border_style=&#8220;solid&#8220; global_module=&#8220;6361&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;]\n<ul>\n<li><a href=\"#1\"><span style=\"color: #fc7c00;\">Mehr Zeit f\u00fcr die wichtigen Dinge<\/span><\/a><\/li>\n<li><a href=\"#2\"><span style=\"color: #fc7c00;\">So einfach geht&#8217;s<\/span><\/a><\/li>\n<li><a href=\"#3\"><span style=\"color: #fc7c00;\">Schritt 1 &#8211; Lehrbuch w\u00e4hlen<\/span><\/a><\/li>\n<li><a href=\"#4\"><span style=\"color: #fc7c00;\">Schritt 2 &#8211; \u00dcbungstyp w\u00e4hlen<\/span><\/a><\/li>\n<li><a href=\"#5\"><span style=\"color: #fc7c00;\">Schritt 3 &#8211; Test sharen<\/span><\/a><\/li>\n<li><a href=\"#6\"><span style=\"color: #fc7c00;\">Schritt 4 &#8211; Bewertung<\/span><\/a><\/li>\n<li><a href=\"#7\"><span style=\"color: #fc7c00;\">Schritt 5 &#8211; Feedback geben<\/span><\/a><\/li>\n<\/ul>\n[\/et_pb_blurb][et_pb_text admin_label=&#8220;Mehr Zeit f\u00fcr die wichtigen Dinge&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<h2 id=\"1\"><span style=\"font-weight: 400;\">Mehr Zeit f\u00fcr die wichtigen Dinge<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Um Ihnen etwas unter die Arme zu greifen, hat phase6 f\u00fcr Sie ein Tool entwickelt, mit welchem Sie Online-Aufgaben mit Vokabeln passend zu Ihrem Lehrbuch erstellen k\u00f6nnen: <a href=\"https:\/\/www.phase-6.de\/schule\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #fc7c00;\">Der Lehrkr\u00e4fte-Assistent<\/span><\/strong><\/a>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vom Aufbau bis zur Bewertung &#8211; alles digital: Mit nur wenigen Mausklicks kreieren Sie einen Vokabeltest f\u00fcr Ihre Klasse<\/span><span style=\"font-weight: 400;\">. <\/span><strong>Erstellen Sie kostenfreie Aufgaben mit Inhalten passgenau zu Ihrem Lehrwerk!<\/strong><span style=\"font-weight: 400;\"> Egal, ob Sie zum Beispiel Englisch mit Access, Latein mit prima.nova oder Franz\u00f6sisch mit D\u00e9couvertes lehren: Mit <a href=\"https:\/\/www.phase-6.de\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #fc7c00;\">phase6 <\/span><\/a><\/span><span style=\"font-weight: 400;\">w\u00e4hlen Sie Ihr <\/span><strong>Lehrbuch<\/strong><span style=\"font-weight: 400;\">, die relevanten <\/span><strong>Lektionen<\/strong><span style=\"font-weight: 400;\">, die gew\u00fcnschten <\/span><strong>\u00dcbungstypen<\/strong><span style=\"font-weight: 400;\"> und markieren <\/span><strong>bis zu 50 Vokabeln pro Test verteilt auf die einzelnen \u00dcbungen<\/strong><span style=\"font-weight: 400;\">. Alles andere regelt die Software \u2013 v\u00f6llig automatisch und doch individuell nach Ihren W\u00fcnschen.\u00a0<\/span><\/p>\n<p class=\"text-p6-grey-dark\"><span style=\"color: #fc7c00;\">\u2713 <\/span>Nutzen Sie Schulbuch-Vokabeln oder selbst erstellte Inhalte.<\/p>\n<p class=\"text-p6-grey-dark\"><span style=\"color: #fc7c00;\">\u2713 <\/span> W\u00e4hlen Sie zur einfachen Aufgabenerstellung aus zahlreichen vorbereiteten \u00dcbungstypen.<\/p>\n<p class=\"text-p6-grey-dark\"><span style=\"color: #fc7c00;\">\u2713 <\/span> Laden Sie die fertigen Tests und \u00dcbungen als PDF herunter oder teilen Sie einen Link zur Online-Bearbeitung.<\/p>\n<p class=\"text-p6-grey-dark\"><span style=\"color: #fc7c00;\">\u2713 <\/span> Die Funktion ist geeignet f\u00fcr alle Sprachen und Klassenstufen.<\/p>\n<p class=\"text-p6-grey-dark\"><span style=\"color: #fc7c00;\">\u2713 <\/span> Kostenlos f\u00fcr Sie und Ihre Sch\u00fcler:innen.<\/p>\n[\/et_pb_text][et_pb_text admin_label=&#8220;So einfach geht&#8217;s&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<h2 id=\"2\">So einfach geht&#8217;s<\/h2>\n<h3 id=\"3\">Schritt 1 &#8211; Lehrbuch w\u00e4hlen<\/h3>\n<p><span style=\"font-weight: 400;\">Suchen Sie sich einfach das <a href=\"https:\/\/www.phase-6.de\/classic\/service\/user\/teacher\/test-generator\/\"><span style=\"color: #fc7c00;\">gew\u00fcnschte Lehrbuch<\/span><\/a> aus.<\/span><\/p>\n[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2021\/11\/Bild1.png&#8220; title_text=&#8220;Bild1&#8243; admin_label=&#8220;Bild Schritt 1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#bcbcbc&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text admin_label=&#8220;Schritt 2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<h3 id=\"4\"><span style=\"font-weight: 400;\">Schritt 2 &#8211; \u00dcbungstyp w\u00e4hlen<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">W\u00e4hlen Sie den gew\u00fcnschten \u00dcbungstyp und jene Vokabeln, die der Test beinhalten soll. Sie k\u00f6nnen bis zu 50 Vokabeln verteilt auf insgesamt sieben verschiedene Aufgabenstellungen ausw\u00e4hlen. Das Aufgabenblatt kann dann beliebig viele \u00dcbungen beinhalten.<\/span><\/p>\n[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2021\/11\/Bild2.png&#8220; title_text=&#8220;Bild2&#8243; admin_label=&#8220;Bild Schritt 2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#bcbcbc&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_toggle title=&#8220;Tabellarische Abfrage&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter Tabellarische Abfrage&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<p>Die gew\u00fcnschten Vokabeln k\u00f6nnen (auch zuf\u00e4llig) aus der entsprechenden Unit ausgew\u00e4hlt werden. Au\u00dferdem kann die Abfragerichtung festgelegt und der Task mit einer individuellen Aufgabenstellung versehen werden.<\/p>\n[\/et_pb_toggle][et_pb_toggle title=&#8220;S\u00e4tze bilden&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter S\u00e4tze bilden&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<p>Die gew\u00fcnschten Vokabeln k\u00f6nnen (auch zuf\u00e4llig) aus der entsprechenden Unit ausgew\u00e4hlt und der Task mit einer individuellen Aufgabenstellung versehen werden. In den fertigen Aufgaben erscheint dann eine Box mit den gew\u00e4hlten Vokabeln, welche dann von den Sch\u00fclerinnen und Sch\u00fclern in eigens kreierten S\u00e4tzen verbaut werden m\u00fcssen.<\/p>\n[\/et_pb_toggle][et_pb_toggle title=&#8220;Textproduktion&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter Textproduktion&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<p>Die gew\u00fcnschten Vokabeln k\u00f6nnen (auch zuf\u00e4llig) aus der entsprechenden Unit ausgew\u00e4hlt und der Task mit einer individuellen Aufgabenstellung versehen werden. In den fertigen Aufgaben m\u00fcssen die Sch\u00fclerinnen und Sch\u00fcler einen Flie\u00dftext verfassen, der die angegebenen Vokabeln enth\u00e4lt.<\/p>\n[\/et_pb_toggle][et_pb_toggle title=&#8220;L\u00fcckens\u00e4tze&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter L\u00fcckens\u00e4tze&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<div class=\"et_pb_toggle et_pb_module et_pb_accordion_item et_pb_accordion_item_3 et_pb_toggle_open\">\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Es stehen zu ausgew\u00e4hlten Vokabeln vorgefertigte L\u00fcckens\u00e4tze zur Auswahl.<\/p>\n<\/div>\n<\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8220;W\u00f6rter verbinden&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter W\u00f6rter verbinden&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<div class=\"et_pb_toggle et_pb_module et_pb_accordion_item et_pb_accordion_item_3 et_pb_toggle_open\">\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Mindestens 3 und maximal 5 Vokabeln werden (auch zuf\u00e4llig) ausgew\u00e4hlt. In den fertigen Aufgaben m\u00fcssen die Sch\u00fclerinnen und Sch\u00fcler die zusammengeh\u00f6renden Wortpaare mit einem Strich verbinden.<\/p>\n<\/div>\n<\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8220;Verbformen&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter Verbformen&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<div class=\"et_pb_toggle et_pb_module et_pb_accordion_item et_pb_accordion_item_3 et_pb_toggle_open\">\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Hier k\u00f6nnen Sie Konjugationen abfragen. Die Auswahl der Verben erfolgt manuell; nach unregelm\u00e4\u00dfigen Verben kann gefiltert werden.<\/p>\n<p>Achtung: Die Abfrage der Verbformen ist unabh\u00e4ngig vom Lehrbuch gestaltet. In der aktuellen Version k\u00f6nnen lediglich Formen entsprechend des ersten Lehrjahres der Fremdsprache ausgew\u00e4hlt werden.<\/p>\n<\/div>\n<\/div>\n[\/et_pb_toggle][et_pb_toggle title=&#8220;Individuelles Textfeld&#8220; icon_color=&#8220;#fc7c00&#8243; admin_label=&#8220;Umschalter Individuelles Textfeld&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<div class=\"et_pb_toggle et_pb_module et_pb_accordion_item et_pb_accordion_item_3 et_pb_toggle_open\">\n<div class=\"et_pb_toggle_content clearfix\">\n<p>Mit diesem Textfeld k\u00f6nnen Sie Anweisungen oder Erkl\u00e4rungen hinzuf\u00fcgen. Au\u00dferdem kann es als Platzhalter f\u00fcr sp\u00e4tere Punkte und Bewertungen dienen oder Sie f\u00fcgen hiermit eine eigene, vom Lehrbuch unabh\u00e4ngige Aufgabe hinzu.<\/p>\n<\/div>\n<\/div>\n[\/et_pb_toggle][et_pb_text admin_label=&#8220;Schritt 3 (1)&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<h3 id=\"5\">Schritt 3 &#8211; Test teilen<\/h3>\n<p>Sobald Sie mit der Erstellung des Tests fertig sind, k\u00f6nnen Sie noch einige Konfigurationsoptionen festlegen, diese umfassen: Deadline, Bearbeitungszeit und eine optionale zus\u00e4tzliche Nachricht. Danach kann der Test entweder als PDF zum Ausdrucken heruntergeladen oder via Link als Online-Aufgabe mit Ihren Sch\u00fclerinnen und Sch\u00fclern geteilt werden.<\/p>\n[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2021\/11\/Bild3.png&#8220; title_text=&#8220;Bild3&#8243; admin_label=&#8220;Bild 1 Schritt 3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#bcbcbc&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text admin_label=&#8220;Schritt 3 (2)&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<p>Ihre Sch\u00fclerinnen und Sch\u00fcler bearbeiten den Vokabeltest ganz einfach online &#8211; am Smartphone, Tablet oder Computer &#8211; ohne Registrierung oder Login. Die Antworten werden automatisch gespeichert und per Mausklick oder nach Ablauf der Bearbeitungszeit automatisch an Sie \u00fcbermittelt.<\/p>\n[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2021\/10\/test-schueler.png&#8220; title_text=&#8220;test sch\u00fcler&#8220; admin_label=&#8220;Bild 2 Schritt 3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#bcbcbc&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text admin_label=&#8220;Schritt 4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<h3 id=\"6\">Schritt 4 &#8211; Bewertung<\/h3>\n<p>Bewerten Sie die Antworten Ihrer Sch\u00fclerinnen und Sch\u00fcler ganz bequem online &#8211; f\u00fcr jede Abgabe einzeln oder zeitsparend nach \u00dcbungen: Gleiche Antworten werden von phase6 geb\u00fcndelt, sodass Sie diese <strong>nur ein Mal bewerten<\/strong> m\u00fcssen!<\/p>\n[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2021\/11\/bild4.png&#8220; title_text=&#8220;bild4&#8243; admin_label=&#8220;Bild Schritt 4 &#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#bcbcbc&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text admin_label=&#8220;Schritt 5&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]\n<h3 id=\"7\">Schritt 5 &#8211; Feedback geben<\/h3>\n<p>Teilen Sie die Ergebnisse mit Ihren Sch\u00fclerinnen und Sch\u00fclern \u00fcber individuelle Ergebnis-Links. Die Sch\u00fclerinnen und Sch\u00fcler schauen sich Ihre Bewertungen dann direkt online an. Bei Bedarf k\u00f6nnen sie die bewerteten Antworten als PDF exportieren.<\/p>\n[\/et_pb_text][et_pb_image src=&#8220;https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2021\/11\/bild5.png&#8220; title_text=&#8220;bild5&#8243; admin_label=&#8220;Bild Schritt 5&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|5px|5px|5px|5px&#8220; border_width_all=&#8220;2px&#8220; border_color_all=&#8220;#bcbcbc&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_button button_url=&#8220;http:\/\/www.phase6.de\/aufgabe-erstellen?utm_source=lkm&#038;utm_medium=blog&#038;utm_campaign=vtg&#8220; url_new_window=&#8220;on&#8220; button_text=&#8220;Jetzt kostenlos testen!&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;25px&#8220; button_bg_color=&#8220;#fc7c00&#8243; background_layout=&#8220;dark&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Das Kontrollieren von Vokabeltests mag ja zuweilen noch witzig sein, angesichts der Antworten einiger Sch\u00fclerinnen und Sch\u00fcler. Das Erstellen der Tests ist jedoch oft eher eint\u00f6nig und vor allem zeitaufw\u00e4ndig. Mit dem phase6 Vokabeltest-Generator geh\u00f6rt diese Arbeit nun aber der Vergangenheit an. Probieren Sie\u2019s aus!<\/p>\n","protected":false},"author":12,"featured_media":7282,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_canonical":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-7264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-methodik-und-didaktik","et-has-post-format-content","et_post_format-et-post-format-standard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Automatisch Vokabeltests erstellen und bewerten - phase6 Magazin<\/title>\n<meta name=\"description\" content=\"Passend zu Ihrem Lehrwerk: Erstellen Sie kostenlos mit nur wenigen Klicks Vokabeltests und Arbeitsbl\u00e4tter mit verschiedenen \u00dcbungstypen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatisch Vokabeltests erstellen und bewerten - phase6 Magazin\" \/>\n<meta property=\"og:description\" content=\"Passend zu Ihrem Lehrwerk: Erstellen Sie kostenlos mit nur wenigen Klicks Vokabeltests und Arbeitsbl\u00e4tter mit verschiedenen \u00dcbungstypen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/\" \/>\n<meta property=\"og:site_name\" content=\"phase6 Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/phase6.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-15T09:15:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T15:29:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2019\/11\/Vokabeltestgenerator.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/\"},\"author\":{\"name\":\"Elisa\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#\\\/schema\\\/person\\\/bf169c670c24011dd7cda54d8f8dcc23\"},\"headline\":\"Automatisch Vokabeltests erstellen und bewerten\",\"datePublished\":\"2026-01-15T09:15:59+00:00\",\"dateModified\":\"2026-02-03T15:29:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/\"},\"wordCount\":1659,\"publisher\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Vokabeltestgenerator.jpg\",\"articleSection\":[\"Methodik &amp; Didaktik\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/\",\"url\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/\",\"name\":\"Automatisch Vokabeltests erstellen und bewerten - phase6 Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Vokabeltestgenerator.jpg\",\"datePublished\":\"2026-01-15T09:15:59+00:00\",\"dateModified\":\"2026-02-03T15:29:36+00:00\",\"description\":\"Passend zu Ihrem Lehrwerk: Erstellen Sie kostenlos mit nur wenigen Klicks Vokabeltests und Arbeitsbl\u00e4tter mit verschiedenen \u00dcbungstypen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Vokabeltestgenerator.jpg\",\"contentUrl\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Vokabeltestgenerator.jpg\",\"width\":1080,\"height\":675,\"caption\":\"Vokabeltestgenerator\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/fuer-lehrkraefte\\\/themen\\\/methodik-didaktik\\\/automatisch-vokabeltests-erstellen-und-bewerten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Automatisch Vokabeltests erstellen und bewerten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/\",\"name\":\"phase6 Magazin\",\"description\":\"Das Magazin f\u00fcr Sprache, Lernen &amp; Lehren\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#organization\",\"name\":\"phase-6 GmbH\",\"url\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/phase6_logo2017.png\",\"contentUrl\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/phase6_logo2017.png\",\"width\":709,\"height\":200,\"caption\":\"phase-6 GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/phase6.de\\\/\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Phase6\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/#\\\/schema\\\/person\\\/bf169c670c24011dd7cda54d8f8dcc23\",\"name\":\"Elisa\",\"url\":\"https:\\\/\\\/www.phase-6.de\\\/magazin\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Automatisch Vokabeltests erstellen und bewerten - phase6 Magazin","description":"Passend zu Ihrem Lehrwerk: Erstellen Sie kostenlos mit nur wenigen Klicks Vokabeltests und Arbeitsbl\u00e4tter mit verschiedenen \u00dcbungstypen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/","og_locale":"de_DE","og_type":"article","og_title":"Automatisch Vokabeltests erstellen und bewerten - phase6 Magazin","og_description":"Passend zu Ihrem Lehrwerk: Erstellen Sie kostenlos mit nur wenigen Klicks Vokabeltests und Arbeitsbl\u00e4tter mit verschiedenen \u00dcbungstypen!","og_url":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/","og_site_name":"phase6 Magazin","article_publisher":"https:\/\/www.facebook.com\/phase6.de\/","article_published_time":"2026-01-15T09:15:59+00:00","article_modified_time":"2026-02-03T15:29:36+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2019\/11\/Vokabeltestgenerator.jpg","type":"image\/jpeg"}],"author":"Elisa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Elisa","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#article","isPartOf":{"@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/"},"author":{"name":"Elisa","@id":"https:\/\/www.phase-6.de\/magazin\/#\/schema\/person\/bf169c670c24011dd7cda54d8f8dcc23"},"headline":"Automatisch Vokabeltests erstellen und bewerten","datePublished":"2026-01-15T09:15:59+00:00","dateModified":"2026-02-03T15:29:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/"},"wordCount":1659,"publisher":{"@id":"https:\/\/www.phase-6.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2019\/11\/Vokabeltestgenerator.jpg","articleSection":["Methodik &amp; Didaktik"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/","url":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/","name":"Automatisch Vokabeltests erstellen und bewerten - phase6 Magazin","isPartOf":{"@id":"https:\/\/www.phase-6.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#primaryimage"},"image":{"@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2019\/11\/Vokabeltestgenerator.jpg","datePublished":"2026-01-15T09:15:59+00:00","dateModified":"2026-02-03T15:29:36+00:00","description":"Passend zu Ihrem Lehrwerk: Erstellen Sie kostenlos mit nur wenigen Klicks Vokabeltests und Arbeitsbl\u00e4tter mit verschiedenen \u00dcbungstypen!","breadcrumb":{"@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#primaryimage","url":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2019\/11\/Vokabeltestgenerator.jpg","contentUrl":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2019\/11\/Vokabeltestgenerator.jpg","width":1080,"height":675,"caption":"Vokabeltestgenerator"},{"@type":"BreadcrumbList","@id":"https:\/\/www.phase-6.de\/magazin\/fuer-lehrkraefte\/themen\/methodik-didaktik\/automatisch-vokabeltests-erstellen-und-bewerten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.phase-6.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Automatisch Vokabeltests erstellen und bewerten"}]},{"@type":"WebSite","@id":"https:\/\/www.phase-6.de\/magazin\/#website","url":"https:\/\/www.phase-6.de\/magazin\/","name":"phase6 Magazin","description":"Das Magazin f\u00fcr Sprache, Lernen &amp; Lehren","publisher":{"@id":"https:\/\/www.phase-6.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.phase-6.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.phase-6.de\/magazin\/#organization","name":"phase-6 GmbH","url":"https:\/\/www.phase-6.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.phase-6.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2017\/07\/phase6_logo2017.png","contentUrl":"https:\/\/www.phase-6.de\/magazin\/wp-content\/uploads\/2017\/07\/phase6_logo2017.png","width":709,"height":200,"caption":"phase-6 GmbH"},"image":{"@id":"https:\/\/www.phase-6.de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phase6.de\/","https:\/\/de.wikipedia.org\/wiki\/Phase6"]},{"@type":"Person","@id":"https:\/\/www.phase-6.de\/magazin\/#\/schema\/person\/bf169c670c24011dd7cda54d8f8dcc23","name":"Elisa","url":"https:\/\/www.phase-6.de\/magazin\/author\/elisa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/posts\/7264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/comments?post=7264"}],"version-history":[{"count":0,"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/posts\/7264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/media\/7282"}],"wp:attachment":[{"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/media?parent=7264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/categories?post=7264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.phase-6.de\/magazin\/wp-json\/wp\/v2\/tags?post=7264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}